{"id":43041,"date":"2024-12-27T17:10:55","date_gmt":"2024-12-27T10:10:55","guid":{"rendered":"https:\/\/frdfund.org\/th\/?p=43041"},"modified":"2024-12-27T17:10:58","modified_gmt":"2024-12-27T10:10:58","slug":"%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8","status":"publish","type":"post","link":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/","title":{"rendered":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" data-id=\"1771\" src=\"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_27-1024x576-1.jpg\" alt=\"\" class=\"wp-image-1771\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"574\" data-id=\"1770\" src=\"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_25-1024x574-1.jpg\" alt=\"\" class=\"wp-image-1770\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"574\" data-id=\"1773\" src=\"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_21-1024x574-1.jpg\" alt=\"\" class=\"wp-image-1773\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" data-id=\"1772\" src=\"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_16-1024x576-1.jpg\" alt=\"\" class=\"wp-image-1772\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" data-id=\"1776\" src=\"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_14-1024x576-1.jpg\" alt=\"\" class=\"wp-image-1776\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" data-id=\"1774\" src=\"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_6-1024x576-1.jpg\" alt=\"\" class=\"wp-image-1774\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" data-id=\"1775\" src=\"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_3-1024x576-1.jpg\" alt=\"\" class=\"wp-image-1775\" \/><\/figure>\n<\/figure>\n<p>The post <a href=\"https:\/\/phetchabun.frdfund.org\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-6\/\">\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01<\/a> appeared first on <a href=\"https:\/\/phetchabun.frdfund.org\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c.<\/p>\n","protected":false},"author":1,"featured_media":43043,"comment_status":"close","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[193,29,55,34],"tags":[],"class_list":["post-43041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-193","category-29","category-55","category--1-"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 - \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e01\u0e23\u0e04\u0e37\u0e2d\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-27T10:10:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-12-27T10:10:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#blogposting\",\"name\":\"\\u0e21\\u0e2d\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01 - \\u0e2a\\u0e33\\u0e19\\u0e31\\u0e01\\u0e07\\u0e32\\u0e19\\u0e01\\u0e2d\\u0e07\\u0e17\\u0e38\\u0e19\\u0e1f\\u0e37\\u0e49\\u0e19\\u0e1f\\u0e39\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\",\"headline\":\"\\u0e21\\u0e2d\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01\",\"author\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/author\\\/admin_frdfund_th\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/frdfund.org\\\/th\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/LINE_ALBUM_\\u0e17\\u0e33\\u0e2a\\u0e35\\u0e0d\\u0e0d\\u0e32\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01\\u0e2a\\u0e2b\\u0e01\\u0e23\\u0e13_241227_27-1024x576-1.jpg\",\"width\":1024,\"height\":576},\"datePublished\":\"2024-12-27T17:10:55+07:00\",\"dateModified\":\"2024-12-27T17:10:58+07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#webpage\"},\"articleSection\":\"- \\u0e40\\u0e1e\\u0e0a\\u0e23\\u0e1a\\u0e39\\u0e23\\u0e13\\u0e4c, \\u0e02\\u0e48\\u0e32\\u0e27\\u0e1b\\u0e23\\u0e30\\u0e0a\\u0e32\\u0e2a\\u0e31\\u0e21\\u0e1e\\u0e31\\u0e19\\u0e18\\u0e4c, \\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04, \\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04\\u0e17\\u0e35\\u0e48 1 (\\u0e20\\u0e32\\u0e04\\u0e40\\u0e2b\\u0e19\\u0e37\\u0e2d)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/frdfund.org\\\/th\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/#listItem\",\"name\":\"\\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/#listItem\",\"position\":2,\"name\":\"\\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04\",\"item\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/#listItem\",\"name\":\"\\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04\\u0e17\\u0e35\\u0e48 1 (\\u0e20\\u0e32\\u0e04\\u0e40\\u0e2b\\u0e19\\u0e37\\u0e2d)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/#listItem\",\"position\":3,\"name\":\"\\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04\\u0e17\\u0e35\\u0e48 1 (\\u0e20\\u0e32\\u0e04\\u0e40\\u0e2b\\u0e19\\u0e37\\u0e2d)\",\"item\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\\\/#listItem\",\"name\":\"- \\u0e40\\u0e1e\\u0e0a\\u0e23\\u0e1a\\u0e39\\u0e23\\u0e13\\u0e4c\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/#listItem\",\"name\":\"\\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\\\/#listItem\",\"position\":4,\"name\":\"- \\u0e40\\u0e1e\\u0e0a\\u0e23\\u0e1a\\u0e39\\u0e23\\u0e13\\u0e4c\",\"item\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#listItem\",\"name\":\"\\u0e21\\u0e2d\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/#listItem\",\"name\":\"\\u0e20\\u0e39\\u0e21\\u0e34\\u0e20\\u0e32\\u0e04\\u0e17\\u0e35\\u0e48 1 (\\u0e20\\u0e32\\u0e04\\u0e40\\u0e2b\\u0e19\\u0e37\\u0e2d)\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#listItem\",\"position\":5,\"name\":\"\\u0e21\\u0e2d\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/category\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\\\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\\\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\\\/#listItem\",\"name\":\"- \\u0e40\\u0e1e\\u0e0a\\u0e23\\u0e1a\\u0e39\\u0e23\\u0e13\\u0e4c\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/#organization\",\"name\":\"\\u0e2a\\u0e33\\u0e19\\u0e31\\u0e01\\u0e07\\u0e32\\u0e19\\u0e01\\u0e2d\\u0e07\\u0e17\\u0e38\\u0e19\\u0e1f\\u0e37\\u0e49\\u0e19\\u0e1f\\u0e39\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\",\"description\":\"\\u0e0a\\u0e48\\u0e27\\u0e22\\u0e40\\u0e2b\\u0e25\\u0e37\\u0e2d\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e01\\u0e23\\u0e04\\u0e37\\u0e2d\\u0e07\\u0e32\\u0e19\\u0e02\\u0e2d\\u0e07\\u0e40\\u0e23\\u0e32\",\"url\":\"https:\\\/\\\/frdfund.org\\\/th\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/author\\\/admin_frdfund_th\\\/#author\",\"url\":\"https:\\\/\\\/frdfund.org\\\/th\\\/author\\\/admin_frdfund_th\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe4880e44c46674772066c2bf7e474bac70a7216b7e6abad0b6c2ef66e3ebc27?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#webpage\",\"url\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/\",\"name\":\"\\u0e21\\u0e2d\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01 - \\u0e2a\\u0e33\\u0e19\\u0e31\\u0e01\\u0e07\\u0e32\\u0e19\\u0e01\\u0e2d\\u0e07\\u0e17\\u0e38\\u0e19\\u0e1f\\u0e37\\u0e49\\u0e19\\u0e1f\\u0e39\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\",\"description\":\"\\u0e27\\u0e31\\u0e19\\u0e17\\u0e35\\u0e48 26 \\u0e18\\u0e31\\u0e19\\u0e27\\u0e32\\u0e04\\u0e21 2567 \\u0e19\\u0e32\\u0e07\\u0e2a\\u0e32\\u0e27\\u0e23\\u0e0a\\u0e15\\u0e27\\u0e23\\u0e23\\u0e13 \\u0e2b\\u0e21\\u0e37\\u0e48\\u0e19\\u0e2a\\u0e32\\u0e22 \\u0e1e\\u0e19\\u0e31\\u0e01\\u0e07\\u0e32\\u0e19\\u0e2d\\u0e32\\u0e27\\u0e38\\u0e42\\u0e2a \\u0e23\\u0e31\\u0e01\\u0e29\\u0e32\\u0e01\\u0e32\\u0e23\\u0e43\\u0e19\\u0e15\\u0e33\\u0e41\\u0e2b\\u0e19\\u0e48\\u0e07\\u0e2b\\u0e31\\u0e27\\u0e2b\\u0e19\\u0e49\\u0e32\\u0e2a\\u0e33\\u0e19\\u0e31\\u0e01\\u0e07\\u0e32\\u0e19\\u0e2a\\u0e32\\u0e02\\u0e32\\u0e08\\u0e31\\u0e07\\u0e2b\\u0e27\\u0e31\\u0e14\\u0e40\\u0e1e\\u0e0a\\u0e23\\u0e1a\\u0e39\\u0e23\\u0e13\\u0e4c \\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e14\\u0e49\\u0e27\\u0e22\\u0e40\\u0e08\\u0e49\\u0e32\\u0e2b\\u0e19\\u0e49\\u0e32\\u0e17\\u0e35\\u0e48 \\u0e23\\u0e48\\u0e27\\u0e21\\u0e21\\u0e2d\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01\\u0e08\\u0e33\\u0e19\\u0e27\\u0e19 2 \\u0e23\\u0e32\\u0e22 \\u0e42\\u0e14\\u0e22\\u0e21\\u0e35\\u0e40\\u0e08\\u0e49\\u0e32\\u0e2b\\u0e19\\u0e49\\u0e32\\u0e17\\u0e35\\u0e48\\u0e2a\\u0e2b\\u0e01\\u0e23\\u0e13\\u0e4c\\u0e01\\u0e32\\u0e23\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e2b\\u0e19\\u0e2d\\u0e07\\u0e44\\u0e1c\\u0e48 \\u0e08\\u0e33\\u0e01\\u0e31\\u0e14 \\u0e40\\u0e1b\\u0e47\\u0e19\\u0e1c\\u0e39\\u0e49\\u0e23\\u0e31\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e08\\u0e33\\u0e19\\u0e27\\u0e19\\u0e40\\u0e07\\u0e34\\u0e19 174,478.30 \\u0e1a\\u0e32\\u0e17 \\u0e01\\u0e2d\\u0e07\\u0e17\\u0e38\\u0e19\\u0e1f\\u0e37\\u0e49\\u0e19\\u0e1f\\u0e39\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e32\\u0e02\\u0e32\\u0e40\\u0e1e\\u0e0a\\u0e23\\u0e1a\\u0e39\\u0e23\\u0e13\\u0e4c\\u0e44\\u0e14\\u0e49\\u0e0a\\u0e35\\u0e49\\u0e41\\u0e08\\u0e07\\u0e17\\u0e33\\u0e04\\u0e27\\u0e32\\u0e21\\u0e40\\u0e02\\u0e49\\u0e32\\u0e43\\u0e08\\u0e41\\u0e25\\u0e30\\u0e08\\u0e31\\u0e14\\u0e17\\u0e33\\u0e19\\u0e34\\u0e15\\u0e34\\u0e01\\u0e23\\u0e23\\u0e21\\u0e2a\\u0e31\\u0e0d\\u0e0d\\u0e32 \\u0e42\\u0e14\\u0e22\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e44\\u0e14\\u0e49\\u0e17\\u0e33\\u0e2a\\u0e31\\u0e0d\\u0e0d\\u0e32\\u0e23\\u0e31\\u0e1a\\u0e20\\u0e32\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e02\\u0e2d\\u0e07\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01\\u0e17\\u0e35\\u0e48\\u0e17\\u0e35\\u0e15\\u0e48\\u0e2d\\u0e01\\u0e2d\\u0e07\\u0e17\\u0e38\\u0e19\\u0e1f\\u0e37\\u0e49\\u0e19\\u0e1f\\u0e39\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23 \\u0e40\\u0e1b\\u0e47\\u0e19\\u0e23\\u0e30\\u0e22\\u0e30\\u0e40\\u0e27\\u0e25\\u0e32\\u0e1c\\u0e48\\u0e2d\\u0e19\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e40\\u0e07\\u0e34\\u0e19\\u0e04\\u0e37\\u0e19 20 \\u0e1b\\u0e35 \\u0e42\\u0e14\\u0e22\\u0e44\\u0e21\\u0e48\\u0e21\\u0e35\\u0e14\\u0e2d\\u0e01\\u0e40\\u0e1a\\u0e35\\u0e49\\u0e22 \\u0e13 \\u0e2a\\u0e2b\\u0e01\\u0e23\\u0e13\\u0e4c\\u0e01\\u0e32\\u0e23\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e2b\\u0e19\\u0e2d\\u0e07\\u0e44\\u0e1c\\u0e48 \\u0e08\\u0e33\\u0e01\\u0e31\\u0e14 The post \\u0e21\\u0e2d\\u0e1a\\u0e40\\u0e0a\\u0e47\\u0e04\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01 appeared first on \\u0e2a\\u0e33\\u0e19\\u0e31\\u0e01\\u0e07\\u0e32\\u0e19\\u0e01\\u0e2d\\u0e07\\u0e17\\u0e38\\u0e19\\u0e1f\\u0e37\\u0e49\\u0e19\\u0e1f\\u0e39\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23 \\u0e2a\\u0e32\\u0e02\\u0e32\\u0e08\\u0e31\\u0e07\\u0e2b\\u0e27\\u0e31\\u0e14\\u0e40\\u0e1e\\u0e0a\\u0e23\\u0e1a\\u0e39\\u0e23\\u0e13\\u0e4c.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/author\\\/admin_frdfund_th\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/author\\\/admin_frdfund_th\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/frdfund.org\\\/th\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/LINE_ALBUM_\\u0e17\\u0e33\\u0e2a\\u0e35\\u0e0d\\u0e0d\\u0e32\\u0e0a\\u0e33\\u0e23\\u0e30\\u0e2b\\u0e19\\u0e35\\u0e49\\u0e41\\u0e17\\u0e19\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\\u0e2a\\u0e21\\u0e32\\u0e0a\\u0e34\\u0e01\\u0e2a\\u0e2b\\u0e01\\u0e23\\u0e13_241227_27-1024x576-1.jpg\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#mainImage\",\"width\":1024,\"height\":576},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\\\/#mainImage\"},\"datePublished\":\"2024-12-27T17:10:55+07:00\",\"dateModified\":\"2024-12-27T17:10:58+07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/frdfund.org\\\/th\\\/\",\"name\":\"\\u0e2a\\u0e33\\u0e19\\u0e31\\u0e01\\u0e07\\u0e32\\u0e19\\u0e01\\u0e2d\\u0e07\\u0e17\\u0e38\\u0e19\\u0e1f\\u0e37\\u0e49\\u0e19\\u0e1f\\u0e39\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e23\\u0e01\\u0e23\",\"description\":\"\\u0e0a\\u0e48\\u0e27\\u0e22\\u0e40\\u0e2b\\u0e25\\u0e37\\u0e2d\\u0e41\\u0e25\\u0e30\\u0e1e\\u0e31\\u0e12\\u0e19\\u0e32\\u0e40\\u0e01\\u0e29\\u0e15\\u0e01\\u0e23\\u0e04\\u0e37\\u0e2d\\u0e07\\u0e32\\u0e19\\u0e02\\u0e2d\\u0e07\\u0e40\\u0e23\\u0e32\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/frdfund.org\\\/th\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23","description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c.","canonical_url":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#blogposting","name":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23","headline":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01","author":{"@id":"https:\/\/frdfund.org\/th\/author\/admin_frdfund_th\/#author"},"publisher":{"@id":"https:\/\/frdfund.org\/th\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_27-1024x576-1.jpg","width":1024,"height":576},"datePublished":"2024-12-27T17:10:55+07:00","dateModified":"2024-12-27T17:10:58+07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#webpage"},"isPartOf":{"@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#webpage"},"articleSection":"- \u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c, \u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c, \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04, \u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1 (\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d)"},{"@type":"BreadcrumbList","@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th#listItem","position":1,"name":"Home","item":"https:\/\/frdfund.org\/th","nextItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/#listItem","name":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04"}},{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/#listItem","position":2,"name":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","item":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/","nextItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/#listItem","name":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1 (\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/#listItem","position":3,"name":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1 (\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d)","item":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\/#listItem","name":"- \u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c"},"previousItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/#listItem","name":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04"}},{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\/#listItem","position":4,"name":"- \u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c","item":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\/","nextItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#listItem","name":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01"},"previousItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/#listItem","name":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1 (\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d)"}},{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#listItem","position":5,"name":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01","previousItem":{"@type":"ListItem","@id":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\/#listItem","name":"- \u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c"}}]},{"@type":"Organization","@id":"https:\/\/frdfund.org\/th\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23","description":"\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e01\u0e23\u0e04\u0e37\u0e2d\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32","url":"https:\/\/frdfund.org\/th\/"},{"@type":"Person","@id":"https:\/\/frdfund.org\/th\/author\/admin_frdfund_th\/#author","url":"https:\/\/frdfund.org\/th\/author\/admin_frdfund_th\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fe4880e44c46674772066c2bf7e474bac70a7216b7e6abad0b6c2ef66e3ebc27?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#webpage","url":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/","name":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23","description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/frdfund.org\/th\/#website"},"breadcrumb":{"@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#breadcrumblist"},"author":{"@id":"https:\/\/frdfund.org\/th\/author\/admin_frdfund_th\/#author"},"creator":{"@id":"https:\/\/frdfund.org\/th\/author\/admin_frdfund_th\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_27-1024x576-1.jpg","@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#mainImage","width":1024,"height":576},"primaryImageOfPage":{"@id":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/#mainImage"},"datePublished":"2024-12-27T17:10:55+07:00","dateModified":"2024-12-27T17:10:58+07:00"},{"@type":"WebSite","@id":"https:\/\/frdfund.org\/th\/#website","url":"https:\/\/frdfund.org\/th\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23","description":"\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e01\u0e23\u0e04\u0e37\u0e2d\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32","inLanguage":"en-US","publisher":{"@id":"https:\/\/frdfund.org\/th\/#organization"}}]},"og:locale":"en_US","og:site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 - \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e01\u0e23\u0e04\u0e37\u0e2d\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32","og:type":"article","og:title":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23","og:description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c.","og:url":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/","article:published_time":"2024-12-27T10:10:55+00:00","article:modified_time":"2024-12-27T10:10:58+00:00","twitter:card":"summary_large_image","twitter:title":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23","twitter:description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e0a\u0e15\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e2a\u0e32\u0e22 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 174,478.30 \u0e1a\u0e32\u0e17 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e17\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19 20 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e13 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e44\u0e1c\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 The post \u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 appeared first on \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c."},"aioseo_meta_data":{"post_id":"43041","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-12-27 10:18:38","updated":"2026-02-10 10:23:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/frdfund.org\/th\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/\" title=\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\">\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/\" title=\"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1 (\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d)\">\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1 (\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d)<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\/\" title=\"- \u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\">- \u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/frdfund.org\/th"},{"label":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04","link":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/"},{"label":"\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e35\u0e48 1 (\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d)","link":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/"},{"label":"- \u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c","link":"https:\/\/frdfund.org\/th\/category\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%97%e0%b8%b5%e0%b9%88-1-%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%80%e0%b8%ab%e0%b8%99%e0%b8%b7%e0%b8%ad\/%e0%b9%80%e0%b8%9e%e0%b8%8a%e0%b8%a3%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%93%e0%b9%8c\/"},{"label":"\u0e21\u0e2d\u0e1a\u0e40\u0e0a\u0e47\u0e04\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01","link":"https:\/\/frdfund.org\/th\/%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%8a%e0%b9%87%e0%b8%84%e0%b8%8a%e0%b8%b3%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%99%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%97%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95-8\/"}],"jetpack_featured_media_url":"https:\/\/frdfund.org\/th\/wp-content\/uploads\/2024\/12\/LINE_ALBUM_\u0e17\u0e33\u0e2a\u0e35\u0e0d\u0e0d\u0e32\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e2b\u0e01\u0e23\u0e13_241227_27-1024x576-1.jpg","_links":{"self":[{"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/posts\/43041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/comments?post=43041"}],"version-history":[{"count":3,"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/posts\/43041\/revisions"}],"predecessor-version":[{"id":43051,"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/posts\/43041\/revisions\/43051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/media\/43043"}],"wp:attachment":[{"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/media?parent=43041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/categories?post=43041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frdfund.org\/th\/wp-json\/wp\/v2\/tags?post=43041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}